{"id":61,"count":3,"description":"Die Kollektion A Veredas umfasst Weine, die aus kleinen Familienweing\u00fctern stammen und sorgf\u00e4ltig hergestellt werden, wobei die Frische der Fr\u00fcchte und der Ausdruck des Terroirs im Vordergrund stehen. Jedes Produkt dieser Reihe zeichnet sich durch seine Ausgewogenheit, Authentizit\u00e4t und einen modernen Stil aus, der die Identit\u00e4t von Galilea und den Charakter des Weinguts widerspiegelt.","link":"https:\/\/nestareseguizabal.com\/de\/tipo-de-vinos\/auf-burgersteige\/","name":"A Veredas","slug":"a-veredas","taxonomy":"product_cat","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/nestareseguizabal.com\/de\/wp-json\/wp\/v2\/product_cat\/61","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nestareseguizabal.com\/de\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/nestareseguizabal.com\/de\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/nestareseguizabal.com\/de\/wp-json\/wp\/v2\/product?product_cat=61"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}